{"id":4367,"date":"2018-06-13T12:19:11","date_gmt":"2018-06-13T12:19:11","guid":{"rendered":"https:\/\/t-safe.com\/privacy-policy\/"},"modified":"2025-02-11T07:55:24","modified_gmt":"2025-02-11T07:55:24","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/t-safe.com\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<h2>Who we are<\/h2>\n<p>Our website address is: http:\/\/t-safe.com\/.<\/p>\n<h2>What personal data we collect and why we collect it<\/h2>\n<h3>Comments<\/h3>\n<p>When visitors leave comments on the site we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection.<\/p>\n<p>An anonymized string created from your email address (also called a hash) may be provided to the Gravatar service to see if you are using it. The Gravatar service privacy policy is available here: https:\/\/automattic.com\/privacy\/. After approval of your comment, your profile picture is visible to the public in the context of your comment.<\/p>\n<h3>Media<\/h3>\n<p>If you upload images to the website, you should avoid uploading images with embedded location data (EXIF GPS) included. Visitors to the website can download and extract any location data from images on the website.<\/p>\n<h3>Contact forms<\/h3>\n<h3>Cookies<\/h3>\n<p>If you leave a comment on our site you may opt-in to saving your name, email address and website in cookies. These are for your convenience so that you do not have to fill in your details again when you leave another comment. These cookies will last for one year.<\/p>\n<p>If you have an account and you log in to this site, we will set a temporary cookie to determine if your browser accepts cookies. This cookie contains no personal data and is discarded when you close your browser.<\/p>\n<p>When you log in, we will also set up several cookies to save your login information and your screen display choices. Login cookies last for two days, and screen options cookies last for a year. If you select &#8220;Remember Me&#8221;, your login will persist for two weeks. If you log out of your account, the login cookies will be removed.<\/p>\n<p>If you edit or publish an article, an additional cookie will be saved in your browser. This cookie includes no personal data and simply indicates the post ID of the article you just edited. It expires after 1 day.<\/p>\n<h3>Embedded content from other websites<\/h3>\n<p>Articles on this site may include embedded content (e.g. videos, images, articles, etc.). Embedded content from other websites behaves in the exact same way as if the visitor has visited the other website.<\/p>\n<p>These websites may collect data about you, use cookies, embed additional third-party tracking, and monitor your interaction with that embedded content, including tracing your interaction with the embedded content if you have an account and are logged in to that website.<\/p>\n<h3>Analytics<\/h3>\n<h2>Who we share your data with<\/h2>\n<h2>How long we retain your data<\/h2>\n<p>If you leave a comment, the comment and its metadata are retained indefinitely. This is so we can recognize and approve any follow-up comments automatically instead of holding them in a moderation queue.<\/p>\n<p>For users that register on our website (if any), we also store the personal information they provide in their user profile. All users can see, edit, or delete their personal information at any time (except they cannot change their username). Website administrators can also see and edit that information.<\/p>\n<h2>What rights you have over your data<\/h2>\n<p>If you have an account on this site, or have left comments, you can request to receive an exported file of the personal data we hold about you, including any data you have provided to us. You can also request that we erase any personal data we hold about you. This does not include any data we are obliged to keep for administrative, legal, or security purposes.<\/p>\n<h2>Where we send your data<\/h2>\n<p>Visitor comments may be checked through an automated spam detection service.<\/p>\n<h2>Your contact information<\/h2>\n<h2>Additional information<\/h2>\n<h3>How we protect your data<\/h3>\n<h3>What data breach procedures we have in place<\/h3>\n<h3>What third parties we receive data from<\/h3>\n<h3>What automated decision making and\/or profiling we do with user data<\/h3>\n<h3>Industry regulatory disclosure requirements<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Who we are Our website address is: http:\/\/t-safe.com\/. What personal data we collect and why we collect it Comments When visitors leave comments on the site we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection. An anonymized string created from [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4367","page","type-page","status-publish","hentry"],"acf":[],"rankMath":{"parentDomain":"t-safe.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"Das angezeigte Beitragsbild sollte mindestens 200x200 px gro\u00df sein, damit Facebook und andere Social-Media-Websites es \u00fcbernehmen.","pluginReviewed":false,"postSettings":{"linkSuggestions":false,"useFocusKeyword":false},"frontEndScore":false,"postName":"datenschutzerklaerung","permalinkFormat":"https:\/\/t-safe.com\/de\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/t-safe.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":false,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"play","facebookAuthor":"","twitterCardType":"summary_large_image","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"play","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"Benutzername","primaryTerm":0,"authorName":"admin","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["abgelenkt","abgesturzt","absolut","abstossend","aburd","abweisen","adaquat","aggressiv","ahnungslos","akkurat","alarmierend","alarmiert","albtraum","all-inclusive","allererste","allererster","allererstes","alleswisser","am schlechtesten","am wichtigsten","angewidert","angriff","angsteinflossend","angstlich","animiert","ankundigung","anonym","anpassbar","anspruchslos","anstossig","antagonistisch","apokalypse","applaus","argumentativ","arm","armageddon","arrogant","atemberaubend","attacke","attraktiv","aufdeckend","aufgebracht","aufgedeckt","aufgeregt","aufheiternd","aufregend","aufregende","aufregenden","aufregung","aufstachelnd","aufstandisch","aufsteigend","auftreibend","augenoffnend","ausgelassen","ausgeruht","ausgespielt","ausgewahlt","ausgewuhlt","ausnutzen","aussergewohnlich","autark","authentisch","autoritat","backdoor","badass","beangstigend","bedenklich","bedingungslos","bedrohen","bedroht","beforderung","befreit","befriedigend","befriedigt","begehren","begeistern","begeistert","begeisterung","beherzt","behind the scenes","beichte","beleidigung","belohnung","bemerkenswert","beneiden","bequem","beruhmt","beschadigen","beschamend","beschmutzt","beschuldigen","beschutzen","besitz","bessesen","bestatigen","bestatigt","beste","bestimmt","bestrafen","betrug","betrugen","bewahrt","bewiesen","bewiesenermassen","bewusst","bezahlbar","bezaubernd","bizarre","bleich","blendend","blut","blutbad","blutig","bombe","bonanza","bonus","bosartig","bose","boshaft","brilliant","brodelnd","brutal","budget","bullshit","bully","bunt","bunte","bunten","case study","cash","challenge","challgene","chaos","cheat-sheet","clever","content","cool","courage","dankbar","daruber redet keiner","deadline","definitiv","dekadent","demoralisierend","demut","desillusioniert","detailiert","diagnose","die wahrheit","direkt","disastros","discount","dokument","dollar","dominieren","doppelt","download","dreckig","dreifach","dreistigkeit","dringend","dringlichkeit","dumm","dummkopf","dummlich","durchbruch","duselig","dynamik","echt","effektiv","effizient","ehrlich","eier","eifersuchtig","eifrig","eindeutig","eindrucksvoll","eine stufe besser","einfach","einfachheit","einfallsreich","eingebildet","eingeschrankt","eingesperrt","einmalig","einsam","eintauchen","einzigartig","eisern","eliminieren","elite","empathie","empfehle","empfehlen","endeffekt","energie","energisch","enorm","entdecken","entfesselt","entfremdet","enthullen","enthullung","enthusiastisch","entmachtet","entsetzlich","entspannt","entzuckend","entzunden","epidemisch","episch","erbarmlich","erfolg","erfolgreich","erfolgsbilanz","erfreut","erfullen","erfullt","ergebnisse","ergreifen","erhaben","erheben","erhohen","erledigt","ermachtigt","ermudet","ernmutigt","ernsthaft","erobern","erroten","errungenschaft","erschaffen","erschrocken","ersehnen","ersparnisse","erstattbar","erstatten","erstaunlich","erste","ertrinken","essentiell","ethisch","euphorisch","exakt","exklusiv","exklusivitat","exkuisit","experte","explodieren","explosiv","exposed","extrem","exzellent","fahig","fahigkeiten","fail","falle","fantasie","fantastischen","farbenfroh","farbenfrohe","faszinierend","faszinierende","faul","faux pas","faux","fehler","feindselig","feldstudie","fesselnd","festlich","festmahl","festplatte","final","flirt","fluchtling","flussig","fokus","fokussiert","folter","formel","frech","freebie","frei","freiheit","freudig","friedlich","frohlich","frohlichkeit","frustriert","fundamental","fur immer","furchtbar","furchtlos","gangster","garantiert","geblendet","geehrt","gefahr","gefahrlich","gefangen","gefangnis","gefeuert","gegensatzlich","gehassig","geheimnis","geheimnisse","geil","geisseln","geist","geistesgestort","gelassen","geld zuruck","geld","genial","gepackt","gerade angekommen","gerissen","geschenk","geschmuggelt","geschutzt","gestandnis","gestandnisse","gestopft","gestresst","gesucht","gesund","getauscht","getestet","getotet","gewaltig","gewalttatig","gewidmet","gewinnspiel","gier","gierig","gift","giftig","gigantisch","giveaway","glamourose","glanzend","glaube","glaubwurdig","gleichmassig","glittering","glitzernde","gluckselig","golden","grandios","grandiose","grandiosen","grandioses","grauenhaft","grausamkeit","grinsen","groesste","gross","grossartig","grossartig","grossartige","grossartigen","grossartiger","grossartiges","grosse","grossen","grosste","grosszugig","grotesk","grube","grundlegend","gruselig","gunstig","hack","hamisch","hammer","handelsgeheimnis","hartnackig","hass","heilig","heimlich","heisshunger","heisshungrig","heiter","held","hell","herablassend","herausfordernd","herausforderung","herausvorderung","herrlichen","herrschend","hervorragend","herz","herzbrechend","herzerwahrmend","heute","hightech","hilflosigkeit","hilfreich","hilfsbereit","himmlisch","hinterhaltig","hoax","hocheffektiv","hochnasig","hochste","hoffnung","hoffnungsvoll","holle","holocaust","horror","how to","humor","hungrige","hurrikan","hypnotisch","hypnotisierend","idiot","idiotisch","illegal","immer","informativ","inhalt","inkompetent","innovativ","insider","inspirierend","inspiriert","intelligent","intensiv","interessant","interessante","invasion","investment","ist da","jackpot","jederzeit kundigen","jetzt","jubilant","jumpstart","jung","kadaver","kampf","katapult","katastrophe","kaufen","kein risiko","keine verpflichtung","kickstart","kindisch","kitschig","klaglich","klar","knast","kollabieren","kollosal","komfortabel","komisch","kompetitiv","komplett","kompromiss","komsich","konstruktiv","kontrollierend","kontrollverlust","kooperativ","kopie","korrupt","kostenlos","kraftlos","kraftvoll","krankhaft","kreativ","kreative","kriese","kritisch","kruppel","lachen","lacherlich","lahm","last minute","lauernd","lebendig","lebenslanglich","lecken","lecker","legendar","legitim","leiche","leicht","leiden","leider","leise","letzte chance","letzte","leuchtend","liberal","licht","liebe","liebenswurdig","liebevoll","life-changing","limitiert","lohnend","loser","losung","lugen","lugend","lukrativ","lust","lustig","lustige","lustigsten","luxorios","magisch","mainstream","mammut","manipulativ","massiv","masterclass","meditierend","meiseter","meistverkauft","meltdown","millionen","mind-blowing","minderwertig","minimalist","missbrauch","misstrauisch","mittelmassig","mittig","modern","moderne","moglichkeiten","monetarisieren","monumental","mord","motiviert","muhelos","muhevoll","mull","mut","mutig","nachmachen","nachteile","nackt","nagel","naiv","natural","nazi","neid","nervos","neu","niedertrachtig","niemals","notfall","notiert","nutzlich","nutzlos","offensichtlich","offiziel","offnen","ohne hintergedanken","ok","okay","okonomisch","on-demand","opfer","optimistisch","overnight","packend","panik","panzer","paralisiert","pas","passioniert","pause","payback","peinlich","perfekt","perplex","perskeptive","pessimistisch","pfund","piranha","pleite","plotzlich","pochend","polarisierend","popular","portfolio","praktisch","preis","prestige","privat","privatsphare","priviligiert","problem","produktiv","professionell","profit","profitabel","provokativ","provozierend","prozess","psychologisch","qual","qualen","qualitat","rabatt","rache","rachsuchtig","raffiniert","rasend","rat","rau","recherche","reduziert","reflektieren","regeln","reich","reiche","reichtum","relaxed","report","responsive","revolutionar","riesig","risiko","riskant","riskieren","rotzfrech","rowdy","ruckrat","ruckschlag","rucksichtlos","ruhig","ruiniert","sabotiert","sadistisch","sale","sarkastisch","scam","schabig","schadigend","schadlich","schamlos","schatz","schicksal","schlachten","schlafen","schlag","schlau","schlimm","schmerzhaft","schmerzlos","schmuggel","schnell","schnellstart","schokierend","schonheit","schrecklich","schreien","schritt fur schritt","schuld","schuldlos","schwach","schwarm","schwarzmarkt","schwerkraft","schwinden","sechsstellig","sehenswerte","selbsthass","selten","sensationell","sex","sexy","sicher","sicherheit","sicherlich","sieg","sill","simpel","sinnlich","sinnlos","skandal","skandalos","skill","sklave","sneak-peek","snob","sofort gespart","sofort","sollte","sonnig","sonnige","sonnigen","sorgen","sorgfaltig","sorglos","spannend","sparen","sparsam","spass","spassig","spektakular","speziell","spielen","spoiler","spontan","spotlight","stabil","stark","start","stoisch","stolz","stop","strahlend","strangulieren","strategie","studien","stumperhaft","stur","sunden","sundigend","super","superb","survival","tapfer","tauschend","teaser","technologie","terror","terrorist","teuer","tief","tiefgreifend","tierisch","tod","todlich","toll","tolle","toller","tortur","tot","tote","toten","totend","toxisch","tragisch","tragodie","transfomieren","transparenz","trauma","traumatisiert","traurigkeit","trend","tricks","trigger","triumpf","trocken","trotz","trugerisch","tweaks","tyrann","ubel","uberfordert","uberkommen","uberleben","uberlegen","uberraschend","uberrascht","uberraschung","uberwaltigend","uberwinden","ultimativ","umfassend","umstritten","umwerfend","unatorisiert","unaufhaltbar","unausgelasted","unbedacht","unbeliebt","unbeschwert","unbewusst","undercover","undokumentiert","unehrlich","unentschlossen","unerwartet","unfahig","ungeduldig","ungedult","ungehort","ungemutlich","ungerechtfertigt","ungesehen","ungetrubt","ungewohnlich","ungezogen","unglaublich","unglaubliches","uninteressiert","unkontrollierbar","unkonventionell","unlimitiert","unpenetrierbar","unschuldig","unsicher","unstabil","unter verschluss","untergrund","unterhaltsam","unterstutz","unterstutzend","unubertroffen","unvergesslich","unverneinbar","unvoreingenommen","unwiderstehlich","unwirtlich","unzensiert","unzuverlassig","up-selling","vaporisieren","verangstigt","verantwortlich","verargert","verarscht","verbessert","verbluffend","verblufft","verboten","verbreiten","verdachtig","verdammt","verdeckt","vereinfacht","verfuhrend","vergebend","vergessen","vergleich","verhauen","verifizieren","verkommen","verlegen","verletzbar","verletzt","verlockend","verloren","vermasselt","vermeiden","vermogen","vernichten","vernichtend","vernunftig","veroffentlichung","verpassen","verraterisch","verruckt","versagen","verschwitzt","versichert","verspielt","versprechend","versteckt","vertrauenswurdig","vertraulich","vertraumt","verurteilend","verwunderlich","verwundet","verzaubernd","verzweifelt","vierfach","vogelfrei","vollig","vollstandig","vorsicht","vorstellungskraft","vorteil","wachstum","wagemutig","wahnsinn","wahnsinnig","wahrhaftig","wahrheit","wahrheitsgemass","wahrscheinlich","warnung","was dir keiner sagt","wehleidig","welt","wenig bekannt","wert","wertvoll","wichtig","widerlich","wiedererkannt","wild","wilde","wilden","willensstarke","wirr","wohltatigkeit","wortlich","wunder","wunderbar","wunderbaren","wunderschon","wutend","zeichen","zeitig","zen","zensiert","zerschlagen","zerschmetternd","zerstorend","zertifiziert","zielorientiert","zischend","zischt","zocken","zogernd","zugeben","zuruckgehalten","zuruckgelassen","zuruckweisen","zusatzlich","zutaten","zuverlassig","zwangsernahrt","zweifelnd","zwickend","zwingend","einfache","einfachen","einfaches","einfacher","simple","simplen","simples","simpler","besten","bestes","bester","beste","bestbewertet","bestbewerteten","bestbewertete","bestbewerteter","bestbewertetes","\u00fcberraschende","\u00fcberraschenden","\u00fcberraschendes","\u00fcberraschender","hilfreiche","hilfreiches","hilfreichen","hilfreicher","f\u00f6rdern","unterst\u00fctzen","helfen","spielerisch","spannende","spannendes","spannenden","spannender","gro\u00dfartige","gro\u00dfartiges","gro\u00dfartigen","gro\u00dfartiger","ideal","ideales","idealen","idealer","faszinierend","faszinierendes","faszinierenden","faszinierender","wichtig","wichtige","wichtiges","wichtigen","wichtiger","sicher","sichere","sicheres","sicheren","sicherer","umfassende","umfassendes","umfassenden","umfassender","ultimative","ultimatives","ultimativen","ultimativer","einzigartige","einzigartiges","einzigartigen","einzigartiger"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2\\u00C4]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OE":"[\\u00D6]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","UE":"[\\u00DC]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3\\u00E4]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oe":"[\\u00f6]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","ue":"[\\u00FC]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":false},"homeUrl":"https:\/\/t-safe.com\/de\/","objectID":4367,"objectType":"post","locale":"de","localeFull":"de_DE","overlayImages":{"play":{"name":"Wiedergabezeichen","url":"https:\/\/t-safe.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhosts\/t-safe.com\/httpdocs\/www\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF-Symbol","url":"https:\/\/t-safe.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhosts\/t-safe.com\/httpdocs\/www\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"http:\/\/t-safe.com\/wp-content\/uploads\/2018\/06\/nhs-water-safety-response-to-covid-19-hero.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Ft-safe.com%2Fde%2F&r=https%3A%2F%2Ft-safe.com%2Fde%2Fwp-json%2Fwp%2Fv2%2Fpages%2F4367%3Fnonce%3Dd9f234de09","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAQCAYAAAAf8\/9hAAABs0lEQVR4AWL4\/\/8\/RRjO8Iucx+noO0MWUDo16FYABMGP6ZfUcRnWtm27jVPbtm3bttuH2t3eFPcY9pLz7NxiLjCyVd87pKnHyqXyxtCs8APd0rnyxiu4qSeA3QEDrAwBDrT1s1Rc\/OrjLZwqVmOSu6+Lamcpp2KKMA9PH1BYXMe1mUP5qotvXTywsOEEYHXxrY+3cqk6TMkYpNr2FeoY3KIr0RPtn9wQ2unlA+GMkRw6+9TFw4YTwDUzx\/JVvARj9KaedXRO8P5B1Du2S32smzqUrcKGEyA+uAgQjKX7zf0boWHGfn71jIKj2689gxp7OAGShNcBUmLMPVjZuiKcA2vuWHHDCQxMCz629kXAIU4ApY15QwggAFbfOP9DhgBJ+nWVJ1AZAfICAj1pAlY6hCADZnveQf7bQIwzVONGJonhLIlS9gr5mFg44Xd+4S3XHoGNPdJl1INIwKyEgHckEhgTe1bGiFY9GSFBYUwLh1IkiJUbY407E7syBSFxKTszEoiE\/YdrgCEayDmtaJwCI9uu8TKMuZSVfSa4BpGgzvomBR\/INhLGzrqDotp01ZR8pn\/1L0JN9d9XNyx0AAAAAElFTkSuQmCC","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Upgraden","trendsPreviewImage":"https:\/\/t-safe.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["abgelenkt","abgesturzt","absolut","abstossend","aburd","abweisen","adaquat","aggressiv","ahnungslos","akkurat","alarmierend","alarmiert","albtraum","all-inclusive","allererste","allererster","allererstes","alleswisser","am schlechtesten","am wichtigsten","angewidert","angriff","angsteinflossend","angstlich","animiert","ankundigung","anonym","anpassbar","anspruchslos","anstossig","antagonistisch","apokalypse","applaus","argumentativ","arm","armageddon","arrogant","atemberaubend","attacke","attraktiv","aufdeckend","aufgebracht","aufgedeckt","aufgeregt","aufheiternd","aufregend","aufregende","aufregenden","aufregung","aufstachelnd","aufstandisch","aufsteigend","auftreibend","augenoffnend","ausgelassen","ausgeruht","ausgespielt","ausgewahlt","ausgewuhlt","ausnutzen","aussergewohnlich","autark","authentisch","autoritat","backdoor","badass","beangstigend","bedenklich","bedingungslos","bedrohen","bedroht","beforderung","befreit","befriedigend","befriedigt","begehren","begeistern","begeistert","begeisterung","beherzt","behind the scenes","beichte","beleidigung","belohnung","bemerkenswert","beneiden","bequem","beruhmt","beschadigen","beschamend","beschmutzt","beschuldigen","beschutzen","besitz","bessesen","bestatigen","bestatigt","beste","bestimmt","bestrafen","betrug","betrugen","bewahrt","bewiesen","bewiesenermassen","bewusst","bezahlbar","bezaubernd","bizarre","bleich","blendend","blut","blutbad","blutig","bombe","bonanza","bonus","bosartig","bose","boshaft","brilliant","brodelnd","brutal","budget","bullshit","bully","bunt","bunte","bunten","case study","cash","challenge","challgene","chaos","cheat-sheet","clever","content","cool","courage","dankbar","daruber redet keiner","deadline","definitiv","dekadent","demoralisierend","demut","desillusioniert","detailiert","diagnose","die wahrheit","direkt","disastros","discount","dokument","dollar","dominieren","doppelt","download","dreckig","dreifach","dreistigkeit","dringend","dringlichkeit","dumm","dummkopf","dummlich","durchbruch","duselig","dynamik","echt","effektiv","effizient","ehrlich","eier","eifersuchtig","eifrig","eindeutig","eindrucksvoll","eine stufe besser","einfach","einfachheit","einfallsreich","eingebildet","eingeschrankt","eingesperrt","einmalig","einsam","eintauchen","einzigartig","eisern","eliminieren","elite","empathie","empfehle","empfehlen","endeffekt","energie","energisch","enorm","entdecken","entfesselt","entfremdet","enthullen","enthullung","enthusiastisch","entmachtet","entsetzlich","entspannt","entzuckend","entzunden","epidemisch","episch","erbarmlich","erfolg","erfolgreich","erfolgsbilanz","erfreut","erfullen","erfullt","ergebnisse","ergreifen","erhaben","erheben","erhohen","erledigt","ermachtigt","ermudet","ernmutigt","ernsthaft","erobern","erroten","errungenschaft","erschaffen","erschrocken","ersehnen","ersparnisse","erstattbar","erstatten","erstaunlich","erste","ertrinken","essentiell","ethisch","euphorisch","exakt","exklusiv","exklusivitat","exkuisit","experte","explodieren","explosiv","exposed","extrem","exzellent","fahig","fahigkeiten","fail","falle","fantasie","fantastischen","farbenfroh","farbenfrohe","faszinierend","faszinierende","faul","faux pas","faux","fehler","feindselig","feldstudie","fesselnd","festlich","festmahl","festplatte","final","flirt","fluchtling","flussig","fokus","fokussiert","folter","formel","frech","freebie","frei","freiheit","freudig","friedlich","frohlich","frohlichkeit","frustriert","fundamental","fur immer","furchtbar","furchtlos","gangster","garantiert","geblendet","geehrt","gefahr","gefahrlich","gefangen","gefangnis","gefeuert","gegensatzlich","gehassig","geheimnis","geheimnisse","geil","geisseln","geist","geistesgestort","gelassen","geld zuruck","geld","genial","gepackt","gerade angekommen","gerissen","geschenk","geschmuggelt","geschutzt","gestandnis","gestandnisse","gestopft","gestresst","gesucht","gesund","getauscht","getestet","getotet","gewaltig","gewalttatig","gewidmet","gewinnspiel","gier","gierig","gift","giftig","gigantisch","giveaway","glamourose","glanzend","glaube","glaubwurdig","gleichmassig","glittering","glitzernde","gluckselig","golden","grandios","grandiose","grandiosen","grandioses","grauenhaft","grausamkeit","grinsen","groesste","gross","grossartig","grossartig","grossartige","grossartigen","grossartiger","grossartiges","grosse","grossen","grosste","grosszugig","grotesk","grube","grundlegend","gruselig","gunstig","hack","hamisch","hammer","handelsgeheimnis","hartnackig","hass","heilig","heimlich","heisshunger","heisshungrig","heiter","held","hell","herablassend","herausfordernd","herausforderung","herausvorderung","herrlichen","herrschend","hervorragend","herz","herzbrechend","herzerwahrmend","heute","hightech","hilflosigkeit","hilfreich","hilfsbereit","himmlisch","hinterhaltig","hoax","hocheffektiv","hochnasig","hochste","hoffnung","hoffnungsvoll","holle","holocaust","horror","how to","humor","hungrige","hurrikan","hypnotisch","hypnotisierend","idiot","idiotisch","illegal","immer","informativ","inhalt","inkompetent","innovativ","insider","inspirierend","inspiriert","intelligent","intensiv","interessant","interessante","invasion","investment","ist da","jackpot","jederzeit kundigen","jetzt","jubilant","jumpstart","jung","kadaver","kampf","katapult","katastrophe","kaufen","kein risiko","keine verpflichtung","kickstart","kindisch","kitschig","klaglich","klar","knast","kollabieren","kollosal","komfortabel","komisch","kompetitiv","komplett","kompromiss","komsich","konstruktiv","kontrollierend","kontrollverlust","kooperativ","kopie","korrupt","kostenlos","kraftlos","kraftvoll","krankhaft","kreativ","kreative","kriese","kritisch","kruppel","lachen","lacherlich","lahm","last minute","lauernd","lebendig","lebenslanglich","lecken","lecker","legendar","legitim","leiche","leicht","leiden","leider","leise","letzte chance","letzte","leuchtend","liberal","licht","liebe","liebenswurdig","liebevoll","life-changing","limitiert","lohnend","loser","losung","lugen","lugend","lukrativ","lust","lustig","lustige","lustigsten","luxorios","magisch","mainstream","mammut","manipulativ","massiv","masterclass","meditierend","meiseter","meistverkauft","meltdown","millionen","mind-blowing","minderwertig","minimalist","missbrauch","misstrauisch","mittelmassig","mittig","modern","moderne","moglichkeiten","monetarisieren","monumental","mord","motiviert","muhelos","muhevoll","mull","mut","mutig","nachmachen","nachteile","nackt","nagel","naiv","natural","nazi","neid","nervos","neu","niedertrachtig","niemals","notfall","notiert","nutzlich","nutzlos","offensichtlich","offiziel","offnen","ohne hintergedanken","ok","okay","okonomisch","on-demand","opfer","optimistisch","overnight","packend","panik","panzer","paralisiert","pas","passioniert","pause","payback","peinlich","perfekt","perplex","perskeptive","pessimistisch","pfund","piranha","pleite","plotzlich","pochend","polarisierend","popular","portfolio","praktisch","preis","prestige","privat","privatsphare","priviligiert","problem","produktiv","professionell","profit","profitabel","provokativ","provozierend","prozess","psychologisch","qual","qualen","qualitat","rabatt","rache","rachsuchtig","raffiniert","rasend","rat","rau","recherche","reduziert","reflektieren","regeln","reich","reiche","reichtum","relaxed","report","responsive","revolutionar","riesig","risiko","riskant","riskieren","rotzfrech","rowdy","ruckrat","ruckschlag","rucksichtlos","ruhig","ruiniert","sabotiert","sadistisch","sale","sarkastisch","scam","schabig","schadigend","schadlich","schamlos","schatz","schicksal","schlachten","schlafen","schlag","schlau","schlimm","schmerzhaft","schmerzlos","schmuggel","schnell","schnellstart","schokierend","schonheit","schrecklich","schreien","schritt fur schritt","schuld","schuldlos","schwach","schwarm","schwarzmarkt","schwerkraft","schwinden","sechsstellig","sehenswerte","selbsthass","selten","sensationell","sex","sexy","sicher","sicherheit","sicherlich","sieg","sill","simpel","sinnlich","sinnlos","skandal","skandalos","skill","sklave","sneak-peek","snob","sofort gespart","sofort","sollte","sonnig","sonnige","sonnigen","sorgen","sorgfaltig","sorglos","spannend","sparen","sparsam","spass","spassig","spektakular","speziell","spielen","spoiler","spontan","spotlight","stabil","stark","start","stoisch","stolz","stop","strahlend","strangulieren","strategie","studien","stumperhaft","stur","sunden","sundigend","super","superb","survival","tapfer","tauschend","teaser","technologie","terror","terrorist","teuer","tief","tiefgreifend","tierisch","tod","todlich","toll","tolle","toller","tortur","tot","tote","toten","totend","toxisch","tragisch","tragodie","transfomieren","transparenz","trauma","traumatisiert","traurigkeit","trend","tricks","trigger","triumpf","trocken","trotz","trugerisch","tweaks","tyrann","ubel","uberfordert","uberkommen","uberleben","uberlegen","uberraschend","uberrascht","uberraschung","uberwaltigend","uberwinden","ultimativ","umfassend","umstritten","umwerfend","unatorisiert","unaufhaltbar","unausgelasted","unbedacht","unbeliebt","unbeschwert","unbewusst","undercover","undokumentiert","unehrlich","unentschlossen","unerwartet","unfahig","ungeduldig","ungedult","ungehort","ungemutlich","ungerechtfertigt","ungesehen","ungetrubt","ungewohnlich","ungezogen","unglaublich","unglaubliches","uninteressiert","unkontrollierbar","unkonventionell","unlimitiert","unpenetrierbar","unschuldig","unsicher","unstabil","unter verschluss","untergrund","unterhaltsam","unterstutz","unterstutzend","unubertroffen","unvergesslich","unverneinbar","unvoreingenommen","unwiderstehlich","unwirtlich","unzensiert","unzuverlassig","up-selling","vaporisieren","verangstigt","verantwortlich","verargert","verarscht","verbessert","verbluffend","verblufft","verboten","verbreiten","verdachtig","verdammt","verdeckt","vereinfacht","verfuhrend","vergebend","vergessen","vergleich","verhauen","verifizieren","verkommen","verlegen","verletzbar","verletzt","verlockend","verloren","vermasselt","vermeiden","vermogen","vernichten","vernichtend","vernunftig","veroffentlichung","verpassen","verraterisch","verruckt","versagen","verschwitzt","versichert","verspielt","versprechend","versteckt","vertrauenswurdig","vertraulich","vertraumt","verurteilend","verwunderlich","verwundet","verzaubernd","verzweifelt","vierfach","vogelfrei","vollig","vollstandig","vorsicht","vorstellungskraft","vorteil","wachstum","wagemutig","wahnsinn","wahnsinnig","wahrhaftig","wahrheit","wahrheitsgemass","wahrscheinlich","warnung","was dir keiner sagt","wehleidig","welt","wenig bekannt","wert","wertvoll","wichtig","widerlich","wiedererkannt","wild","wilde","wilden","willensstarke","wirr","wohltatigkeit","wortlich","wunder","wunderbar","wunderbaren","wunderschon","wutend","zeichen","zeitig","zen","zensiert","zerschlagen","zerschmetternd","zerstorend","zertifiziert","zielorientiert","zischend","zischt","zocken","zogernd","zugeben","zuruckgehalten","zuruckgelassen","zuruckweisen","zusatzlich","zutaten","zuverlassig","zwangsernahrt","zweifelnd","zwickend","zwingend","einfache","einfachen","einfaches","einfacher","simple","simplen","simples","simpler","besten","bestes","bester","beste","bestbewertet","bestbewerteten","bestbewertete","bestbewerteter","bestbewertetes","\u00fcberraschende","\u00fcberraschenden","\u00fcberraschendes","\u00fcberraschender","hilfreiche","hilfreiches","hilfreichen","hilfreicher","f\u00f6rdern","unterst\u00fctzen","helfen","spielerisch","spannende","spannendes","spannenden","spannender","gro\u00dfartige","gro\u00dfartiges","gro\u00dfartigen","gro\u00dfartiger","ideal","ideales","idealen","idealer","faszinierend","faszinierendes","faszinierenden","faszinierender","wichtig","wichtige","wichtiges","wichtigen","wichtiger","sicher","sichere","sicheres","sicheren","sicherer","umfassende","umfassendes","umfassenden","umfassender","ultimative","ultimatives","ultimativen","ultimativer","einzigartige","einzigartiges","einzigartigen","einzigartiger"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/t-safe.com\/de\/wp-json\/wp\/v2\/pages\/4367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/t-safe.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/t-safe.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/t-safe.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/t-safe.com\/de\/wp-json\/wp\/v2\/comments?post=4367"}],"version-history":[{"count":2,"href":"https:\/\/t-safe.com\/de\/wp-json\/wp\/v2\/pages\/4367\/revisions"}],"predecessor-version":[{"id":18292,"href":"https:\/\/t-safe.com\/de\/wp-json\/wp\/v2\/pages\/4367\/revisions\/18292"}],"wp:attachment":[{"href":"https:\/\/t-safe.com\/de\/wp-json\/wp\/v2\/media?parent=4367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}