{"id":5105,"date":"2020-04-23T08:50:57","date_gmt":"2020-04-23T08:50:57","guid":{"rendered":"https:\/\/t-safe.com\/about\/"},"modified":"2024-10-07T09:44:40","modified_gmt":"2024-10-07T09:44:40","slug":"about","status":"publish","type":"page","link":"https:\/\/t-safe.com\/nl\/about\/","title":{"rendered":"Over"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5105","page","type-page","status-publish","hentry"],"acf":[],"rankMath":{"parentDomain":"t-safe.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"De weergegeven afbeelding moet minimaal 200 bij 200 pixels groot zijn om te worden opgepikt door Facebook en andere sociale mediasites.","pluginReviewed":false,"postSettings":{"linkSuggestions":false,"useFocusKeyword":false},"frontEndScore":false,"postName":"about","permalinkFormat":"https:\/\/t-safe.com\/nl\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/t-safe.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":false,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"T-safe,Johs. Tandrup A\/S,Water safety,Legionella filtration","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"play","facebookAuthor":"","twitterCardType":"summary_large_image","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"play","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"gebruikersnaam","primaryTerm":0,"authorName":"admin","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["aanbevelen","aangemoedigd","aangrijpende","aankondigen","aanpasbaar","aanpassingen","aantrekkelijke","aanval","aanvraag","aanzienlijke","aarzelende","absoluut","absoluut laagste","absurd","achter scenes","achterbaks","achterdeur","achtergelaten","adembenemende","adequaat","advies","afgeleid","afgeslagen","afgestreept","afgetekend","afgrijselijk","afgunst","aframmelen","aframmeling","afranselen","afrekenen","afval","aggressief","alarmerend","alles-inclusief","altijd","alwetend","amp","angstaanjagende","angstig","annuleer ieder moment","anoniem","apocalypse","arm","armageddon","arrogant","authentiek","autoriteit","baanbrekende","bang","basis","baviaan","beargumenteerd","bedelen","bedreigde","bedreigen","bedriegen","bedrog","bedrogen","begeesterd","beginner","begrip","behoren","bekentenis","bekeren","belachelijk","belangrijk","belangrijkste","belasterd","belastingdienst","beledigend","belediging","beloning","benadruk","benangstigend","beoordelend","bepaalde","beperkt","beproeving","bereiken","berispend","beroemd","beschaamd","beschadigend","beschamen","beschamend","bescheiden","beschermde","beschermen","beschuldigen","besluiteloos","besparingen","beste","betaal niets","betaalbaar","beter","betoverd","betoverend","betreurenswaardig","betrouwbaar","beveiliging","bevordern","bevredigd","bevreesd","bevrijd","bewezen","bewust","bezeten","biechten","biljoen","bleek","bloed","bloedbad","bloedig","bloedstollend","blootgesteld","blozend","blunder","boef","boeien","boeiend","bom","bona","bona fide","bonus","boos","bovenmenselijk","brandend","breken","brekend","briljant","bruis","bruisend","bruist","brutaal","budget","buitengewone","buitensporigheid","bullshit","capabel","case study","cataclysmische","catastrofe","cheat-sheet","comfortabel","compleet","compromis","compulsief","concurrerend","constructief","contant","controle","controleer","controlerend","controversieel","corrumperende","corrupt","creatief","crisis","dalen","dankbaar","dapper","dapperheid","dartel","de waarheid","deadline","decadent","definitief","demoraliserende","desperaat","diep","direct","directe besparingen","document","dodelijk","doden","dolblij","dollar","dom","domineren","dood","doodsbang","doodt","doofpot","doorbraak","download","drang","dreigend","dreigende","driedubbel","dringend","droefenis","dromerig","dubbel","duidelijk","duidelijkheid","duiken","duur","dynamisch","echt","een beetje meer","eenvoud","eenzaam","eerlijk","eerste","effectief","efficient","eigen agenda","elimineer","elite","empowered","energie","energiek","eng","enorm","enorme","enthousiast","epidemisch","episch","erkende","ernstige","ervaren","essentieel","ethisch","etter","euforisch","exclusieve","exclusiviteit","expert","explosief","extra","extreem","eye-opening","failliet","falen","fantasie","fantastisch","fascinerend","feest","feestelijke","fide","fijn","finaal","flauwte","flirt","focus","formule","fortuin","fout","fundamenten","geaaid","geaard","geanimeerd","gebalanceerd","gebruiken","gecensureerd","gecentreerd","gecertificeerd","gedenkwaardig","gedesorienteerd","gedetailleerde","gediagnosticeerd","gedood","geduld","geeerd","geen idee","geergerd","geest","gefrustreerd","gegarandeerd","geheim","geheim motief","geheimen","geinsprireerd","gek","geld","geld terug","geleidelijk","geleverd","geloof","geluk","gelukkig","gemakkelijk","gemotiveerde","genie","genoegen","genoteerd","geobsedeerd","gepaniekeerd","gepassioneerd","gepriviligeerd","gerichte","geschokt","geschonden","geselecteerde","gesmokkeld","gespannen","gespeeld","getest","getraumatiseerd","gevaar","gevaarlijk","gevaarlijke","gevangenis","geweldadig","geweldig","gewond","gezaghebbende","gezegend","gezocht","gift","giftig","giftige","gigantische","gil","glamoureus","gloeiend","glorieus","gluiperig","goed verkopend","goedgekeurd","goedkeuren","goedkoop","gokkend","gracieus","grappig","grappigst","gratis","gretig","grijpen","groei","grondig","groot","grootsheid","grootste","gruwelijke","haast","hand liggend","handelsgeheim","handig","handige","hart","hartverscheurend","hartverwarmend","hatelijk","haten","heb gehoord gezond","hebzucht","heerlijk verrukkelijk","heftig","heilig","heimelijk","hel","helaas","held","helder","hemeld","herzien","high tech","hilarische","hoe","hoffelijk","hoogst effectief","hoogste","hoop","hoopvol","horror","houden van plezier","hulpeloosheid","humor","hunkeren","hypnotisch","idioot","ijzeren","ijzersterk","illegaal","impopulair","in val","inbreken","incapabel","incompetent","incvasie","indrukwekkende","inferieur","informatieve","ingredienten","inhaligheid","innovatief","insider","inspirerend","instabiele","instorten","intelligent","intens","interessante","intrigerende","introductie","investering","is hier","jackpot","jaloers","jeugdige","joviaal","jubelend","juichen","kadaver","kalm","kans","kansen","katapult","kernsmelting","kickstart","kinderachtig","kipsimpel","kleurrijke","knal","kolosaal","kolossaal","koop","koopje","kopie","koppig","korting","kostbaar","krachtig","krachtige","kreupel","kritische","kwaadaardig","kwaliteit","kwetsbare","laatste","laatste kans","lach","lachen","lachend","lafaard","laffe","lam","lancering","last minute","leerzaam","lef","legendarisch","legitiem","letterlijk","leugens","leven","levend","levendig","levensveranderende","liberaal","licht","liefde","liegen","lijden","lijk","likken","loeren","losbandig","losgelaten","loslaten","luchthartige","lucratief","lui","lust","luxe","luxueus","maak","machteloos","magisch","magsich","mainstream","makkelijk","mammoet","manipulatieve","marteling","massief","masterclass","meditatief","meedogenloos","meester","meewerkend","memorabel","meteen","middelmatig","minachtend","minachtende","minimalistische","misbruik","misleidende","mislukking","misvatting","moed","moedig","moeite","moeiteloos","monumentaal","mooi","moord","mysterie","naakt","nachtmerrie","nadelen","nagel","natuurlijk","nauwgezette","nazi","nederigheid","neerbuigend","neerwaartse spiraal","nerveus","net binnen","niet responsief","nieuwe","nieuwigheid","nog steeds","noodgeval","noodlot","nooit","nutteloos","nuttig","obsessie","offensief","officiele","officieus","okay","omvormen","onaangename","onbekwaam","onbelast","onbenut","onbeperkt","onbetaalbaar","onbetrouwbare","onbevooroordeeld","onbewogen","onbewust","onbezonnen","onconventioneel","onder aan de streep","onderbenut","ondergronds","onderhandse","onderprijsd","ondersteund","ondersteunde","ondersteunend","onderzoek","ondeugend","ondeugende","ondoordringbaar","ondragelijk","oneerlijk","oneven","onfeilbaar","ongeautoriseerde","ongebruikelijke","ongecensureerd","ongecontroleerd","ongeduld","ongeduldig","ongeevenaarde","ongehaast","ongehoord","ongeinteresseerd","ongelooflijk","ongelovelijk","ongemakkelijk","ongezien","ongrijpbaar","onmiddellijk","onnozel","onontkenbaar","onovertroffen","onschuldig","ontbreekt","ontdekken","ontdekt","onterecht","ontgoocheld","onthullen","onthullend","onthutsend","ontkracht","ontploffen","ontslagen","ontsteken","ontzagwekkend","onveilige","onverbiddelijk","onvergetelijk","onverschillig","onverschrokken","onverschrokkenheid","onvervalste","onverwachte","onvoorwaardelijke","onweerstaanbaar","onzeker","op zwarte lijst","opbiechten","openen","opgelijnd","opgetild","opgetogen","opgewonden","opkomend","oplossing","opmerkelijk","opnieuw maken","oprechte","optimistisch","opwindend","opzienbarend","overbelasten","overleef","overleven","overtuigend","overvloedig","overweldigd","overwinnen","paniek","pas op","perfect","perspectief","pessimistisch","pest blij","pestkop","piek","pijn","pijnlijke","pijnloos","piranha","pittig","plagen","plotseling","plukken","pond","populair","portfolio","positief","prachtig","praktische","precies","prestige","prijs","privacy","prive","probleem","productieve","professioneel","propvol","provoceren","provocerende","psychologische","radeloos","rampzalig","rand","rapport","ravage","razernij","rebellerend","recessie bestendig","recessie-proof","rechtszaak","redden","reflecterende","regels","repliceren","represailles","repulsive","reputatie","responsief","restitutie","resultaten","reusachtig","revolutionair","rijden","rijk klinken","rijkdom","rijkelijk","risico","riskant","ruggegraat","ruig","ruine","rustig","saboteren","sadistische","sarcastisch","schaamteloos","schaars","schadelijk","schadelijke","schandaal","schandalig","schat","schattig","scheef","schokkend","schoon genoeg","schoonheid","schreeuw","schudden","schuld","schuldgevoel","sensationeel","sensueel","sereen","serieus","sex","sexy","simpel","simplistisch","slaaf","slaan","slachting","slachtoffer","slapend","slecht","slecht ingehouden","slechtste","slim","slinks","slonzig","sluw","smachten","smakeloos","smerig","smokkelen","snel","snel-start","snob","snotterend","snotterig","solide","spannende","sparen","speciaal","spectaculair","speelse","spelbreker","spervuur","spijker","spontaan","spotlight","stabiel","stap polarisatie","stap-voor-stap","stelen","sterk","sterk aanraden","stevige","stijgend","stijgende","stil","stoer","stoicijns","stom slagen","stomend","stoot","stop","stoppen","storm","straffen","stralend","strategie","streng","stressed","strijd","strijden","studies","stuipen","stuntelen","subliem","succes","succesvol","suffig","super","superbe","superieur","tank","technologie","tegenstelling","tekenen","teneergeslagen","terreur","terrorist","terug te betalen","terugbetalen","terugslag","tevreden","tijdige","toegeeflijk","toegeven","toegewijd","toename","toetakelen","tollen","tragedie","tragisch","transparantie","trauma","trefzekere","trend","triggers","triomf","trots","trucs","twijfel","twijfelachtig","twistziek","uit balans","uitbundig","uitdaging","uitgebreid","uitgehongerd","uitgelaten","uitgerust","uitzinnig","ultiem","undercover","uniek","up-sell","vaardigheid","val","valideren","valkuil","vandaag","vasthoudend","vechten","veelbelovende","veilig","veiligheid","venijnig","veraderlijk","verantwoordelijk","verbazend","verbazingwekkend","verbeelding","verbeterde","verblind","verblinden","verboden","verborgen","verdacht","verdampen","verdienen","verdoemd","verdomme","verdorven","verdrinken","vereenvoudigd","verergeren","vergelijk","vergeten","vergevend","verheffend","verkoop","verlamd","verlangen","verleidelijk","verleidelijke","verlicht","verliezer","verloren","vermijd","verminderde","vermoeide","vernietigen","verontrust","veroordelen","veroveren","verpakt","verpletterd","verpletteren","verplichting","verraderlijke","verrassend","verrassende","verrassing","verrast","verrukt","verschrikkelijk","verslaan","verspillen","verstrikt","vertrouwelijk","vertrouwen","vertrouwend","vervbodern","vervreemd","vervuld","vervullen","verwaand","verward","verwoestende","verwoesting","verzamelaar","verzekerd","verzet","verzettend","vet","vierdubbel","vijandig","vindingrijk","vloeibaar","vluchteling","volatiel","volledig","volledigheid","voor altijd","voordeel","voorproef","voortreffelijk","voorzichtig","vreemd","vreselijk","vrijheid","vrijlaten","vrolijk","vuil spel","vurig","waanzinnig","waanzinnige","waar over praat","waarde","waardevolle","waarheid","waarschijnlijk","waarschuwing","wachtend","walgelijk","wankelende","wantrouwend","wat niemand je vertelt","watertanden","weerzinwekkend","weerzinwekkende","weggever","weigeren","weinig bekend","wens","wereld","wild","wilskracht","winst","winstgevende","woedend","wonderful","wonderlijk","wraak","wraakzuchtig","wreed","wreedheid","wulpse","wurgen","zalig","zege","zeker","zeldzaam","zelfgenoegzaam","zelfhatende","zelfverzekerd","zelfvoorzienend","zen","zes-cijferige","ziedend","zielig","zinger","zinloos","zomaar","zonden","zonder vrees","zondig","zonnig","zorgeloos","zorgen zorg","zorgvuldig","zou","zuigen","zuinig","zwaartekracht","zwakke","zwarte markt","zweep","zwetend","zwijmelend"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":false},"homeUrl":"https:\/\/t-safe.com\/nl\/","objectID":5105,"objectType":"post","locale":"nl","localeFull":"nl_NL","overlayImages":{"play":{"name":"Afspeel pictogram","url":"https:\/\/t-safe.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/vhosts\/t-safe.com\/httpdocs\/www\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF pictogram","url":"https:\/\/t-safe.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/vhosts\/t-safe.com\/httpdocs\/www\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"http:\/\/t-safe.com\/wp-content\/uploads\/2018\/06\/nhs-water-safety-response-to-covid-19-hero.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Ft-safe.com%2Fnl%2F&r=https%3A%2F%2Ft-safe.com%2Fnl%2Fwp-json%2Fwp%2Fv2%2Fpages%2F5105%3Fnonce%3Dd9f234de09","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAQCAYAAAAf8\/9hAAABs0lEQVR4AWL4\/\/8\/RRjO8Iucx+noO0MWUDo16FYABMGP6ZfUcRnWtm27jVPbtm3bttuH2t3eFPcY9pLz7NxiLjCyVd87pKnHyqXyxtCs8APd0rnyxiu4qSeA3QEDrAwBDrT1s1Rc\/OrjLZwqVmOSu6+Lamcpp2KKMA9PH1BYXMe1mUP5qotvXTywsOEEYHXxrY+3cqk6TMkYpNr2FeoY3KIr0RPtn9wQ2unlA+GMkRw6+9TFw4YTwDUzx\/JVvARj9KaedXRO8P5B1Du2S32smzqUrcKGEyA+uAgQjKX7zf0boWHGfn71jIKj2689gxp7OAGShNcBUmLMPVjZuiKcA2vuWHHDCQxMCz629kXAIU4ApY15QwggAFbfOP9DhgBJ+nWVJ1AZAfICAj1pAlY6hCADZnveQf7bQIwzVONGJonhLIlS9gr5mFg44Xd+4S3XHoGNPdJl1INIwKyEgHckEhgTe1bGiFY9GSFBYUwLh1IkiJUbY407E7syBSFxKTszEoiE\/YdrgCEayDmtaJwCI9uu8TKMuZSVfSa4BpGgzvomBR\/INhLGzrqDotp01ZR8pn\/1L0JN9d9XNyx0AAAAAElFTkSuQmCC","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Upgrade","trendsPreviewImage":"https:\/\/t-safe.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["aanbevelen","aangemoedigd","aangrijpende","aankondigen","aanpasbaar","aanpassingen","aantrekkelijke","aanval","aanvraag","aanzienlijke","aarzelende","absoluut","absoluut laagste","absurd","achter scenes","achterbaks","achterdeur","achtergelaten","adembenemende","adequaat","advies","afgeleid","afgeslagen","afgestreept","afgetekend","afgrijselijk","afgunst","aframmelen","aframmeling","afranselen","afrekenen","afval","aggressief","alarmerend","alles-inclusief","altijd","alwetend","amp","angstaanjagende","angstig","annuleer ieder moment","anoniem","apocalypse","arm","armageddon","arrogant","authentiek","autoriteit","baanbrekende","bang","basis","baviaan","beargumenteerd","bedelen","bedreigde","bedreigen","bedriegen","bedrog","bedrogen","begeesterd","beginner","begrip","behoren","bekentenis","bekeren","belachelijk","belangrijk","belangrijkste","belasterd","belastingdienst","beledigend","belediging","beloning","benadruk","benangstigend","beoordelend","bepaalde","beperkt","beproeving","bereiken","berispend","beroemd","beschaamd","beschadigend","beschamen","beschamend","bescheiden","beschermde","beschermen","beschuldigen","besluiteloos","besparingen","beste","betaal niets","betaalbaar","beter","betoverd","betoverend","betreurenswaardig","betrouwbaar","beveiliging","bevordern","bevredigd","bevreesd","bevrijd","bewezen","bewust","bezeten","biechten","biljoen","bleek","bloed","bloedbad","bloedig","bloedstollend","blootgesteld","blozend","blunder","boef","boeien","boeiend","bom","bona","bona fide","bonus","boos","bovenmenselijk","brandend","breken","brekend","briljant","bruis","bruisend","bruist","brutaal","budget","buitengewone","buitensporigheid","bullshit","capabel","case study","cataclysmische","catastrofe","cheat-sheet","comfortabel","compleet","compromis","compulsief","concurrerend","constructief","contant","controle","controleer","controlerend","controversieel","corrumperende","corrupt","creatief","crisis","dalen","dankbaar","dapper","dapperheid","dartel","de waarheid","deadline","decadent","definitief","demoraliserende","desperaat","diep","direct","directe besparingen","document","dodelijk","doden","dolblij","dollar","dom","domineren","dood","doodsbang","doodt","doofpot","doorbraak","download","drang","dreigend","dreigende","driedubbel","dringend","droefenis","dromerig","dubbel","duidelijk","duidelijkheid","duiken","duur","dynamisch","echt","een beetje meer","eenvoud","eenzaam","eerlijk","eerste","effectief","efficient","eigen agenda","elimineer","elite","empowered","energie","energiek","eng","enorm","enorme","enthousiast","epidemisch","episch","erkende","ernstige","ervaren","essentieel","ethisch","etter","euforisch","exclusieve","exclusiviteit","expert","explosief","extra","extreem","eye-opening","failliet","falen","fantasie","fantastisch","fascinerend","feest","feestelijke","fide","fijn","finaal","flauwte","flirt","focus","formule","fortuin","fout","fundamenten","geaaid","geaard","geanimeerd","gebalanceerd","gebruiken","gecensureerd","gecentreerd","gecertificeerd","gedenkwaardig","gedesorienteerd","gedetailleerde","gediagnosticeerd","gedood","geduld","geeerd","geen idee","geergerd","geest","gefrustreerd","gegarandeerd","geheim","geheim motief","geheimen","geinsprireerd","gek","geld","geld terug","geleidelijk","geleverd","geloof","geluk","gelukkig","gemakkelijk","gemotiveerde","genie","genoegen","genoteerd","geobsedeerd","gepaniekeerd","gepassioneerd","gepriviligeerd","gerichte","geschokt","geschonden","geselecteerde","gesmokkeld","gespannen","gespeeld","getest","getraumatiseerd","gevaar","gevaarlijk","gevaarlijke","gevangenis","geweldadig","geweldig","gewond","gezaghebbende","gezegend","gezocht","gift","giftig","giftige","gigantische","gil","glamoureus","gloeiend","glorieus","gluiperig","goed verkopend","goedgekeurd","goedkeuren","goedkoop","gokkend","gracieus","grappig","grappigst","gratis","gretig","grijpen","groei","grondig","groot","grootsheid","grootste","gruwelijke","haast","hand liggend","handelsgeheim","handig","handige","hart","hartverscheurend","hartverwarmend","hatelijk","haten","heb gehoord gezond","hebzucht","heerlijk verrukkelijk","heftig","heilig","heimelijk","hel","helaas","held","helder","hemeld","herzien","high tech","hilarische","hoe","hoffelijk","hoogst effectief","hoogste","hoop","hoopvol","horror","houden van plezier","hulpeloosheid","humor","hunkeren","hypnotisch","idioot","ijzeren","ijzersterk","illegaal","impopulair","in val","inbreken","incapabel","incompetent","incvasie","indrukwekkende","inferieur","informatieve","ingredienten","inhaligheid","innovatief","insider","inspirerend","instabiele","instorten","intelligent","intens","interessante","intrigerende","introductie","investering","is hier","jackpot","jaloers","jeugdige","joviaal","jubelend","juichen","kadaver","kalm","kans","kansen","katapult","kernsmelting","kickstart","kinderachtig","kipsimpel","kleurrijke","knal","kolosaal","kolossaal","koop","koopje","kopie","koppig","korting","kostbaar","krachtig","krachtige","kreupel","kritische","kwaadaardig","kwaliteit","kwetsbare","laatste","laatste kans","lach","lachen","lachend","lafaard","laffe","lam","lancering","last minute","leerzaam","lef","legendarisch","legitiem","letterlijk","leugens","leven","levend","levendig","levensveranderende","liberaal","licht","liefde","liegen","lijden","lijk","likken","loeren","losbandig","losgelaten","loslaten","luchthartige","lucratief","lui","lust","luxe","luxueus","maak","machteloos","magisch","magsich","mainstream","makkelijk","mammoet","manipulatieve","marteling","massief","masterclass","meditatief","meedogenloos","meester","meewerkend","memorabel","meteen","middelmatig","minachtend","minachtende","minimalistische","misbruik","misleidende","mislukking","misvatting","moed","moedig","moeite","moeiteloos","monumentaal","mooi","moord","mysterie","naakt","nachtmerrie","nadelen","nagel","natuurlijk","nauwgezette","nazi","nederigheid","neerbuigend","neerwaartse spiraal","nerveus","net binnen","niet responsief","nieuwe","nieuwigheid","nog steeds","noodgeval","noodlot","nooit","nutteloos","nuttig","obsessie","offensief","officiele","officieus","okay","omvormen","onaangename","onbekwaam","onbelast","onbenut","onbeperkt","onbetaalbaar","onbetrouwbare","onbevooroordeeld","onbewogen","onbewust","onbezonnen","onconventioneel","onder aan de streep","onderbenut","ondergronds","onderhandse","onderprijsd","ondersteund","ondersteunde","ondersteunend","onderzoek","ondeugend","ondeugende","ondoordringbaar","ondragelijk","oneerlijk","oneven","onfeilbaar","ongeautoriseerde","ongebruikelijke","ongecensureerd","ongecontroleerd","ongeduld","ongeduldig","ongeevenaarde","ongehaast","ongehoord","ongeinteresseerd","ongelooflijk","ongelovelijk","ongemakkelijk","ongezien","ongrijpbaar","onmiddellijk","onnozel","onontkenbaar","onovertroffen","onschuldig","ontbreekt","ontdekken","ontdekt","onterecht","ontgoocheld","onthullen","onthullend","onthutsend","ontkracht","ontploffen","ontslagen","ontsteken","ontzagwekkend","onveilige","onverbiddelijk","onvergetelijk","onverschillig","onverschrokken","onverschrokkenheid","onvervalste","onverwachte","onvoorwaardelijke","onweerstaanbaar","onzeker","op zwarte lijst","opbiechten","openen","opgelijnd","opgetild","opgetogen","opgewonden","opkomend","oplossing","opmerkelijk","opnieuw maken","oprechte","optimistisch","opwindend","opzienbarend","overbelasten","overleef","overleven","overtuigend","overvloedig","overweldigd","overwinnen","paniek","pas op","perfect","perspectief","pessimistisch","pest blij","pestkop","piek","pijn","pijnlijke","pijnloos","piranha","pittig","plagen","plotseling","plukken","pond","populair","portfolio","positief","prachtig","praktische","precies","prestige","prijs","privacy","prive","probleem","productieve","professioneel","propvol","provoceren","provocerende","psychologische","radeloos","rampzalig","rand","rapport","ravage","razernij","rebellerend","recessie bestendig","recessie-proof","rechtszaak","redden","reflecterende","regels","repliceren","represailles","repulsive","reputatie","responsief","restitutie","resultaten","reusachtig","revolutionair","rijden","rijk klinken","rijkdom","rijkelijk","risico","riskant","ruggegraat","ruig","ruine","rustig","saboteren","sadistische","sarcastisch","schaamteloos","schaars","schadelijk","schadelijke","schandaal","schandalig","schat","schattig","scheef","schokkend","schoon genoeg","schoonheid","schreeuw","schudden","schuld","schuldgevoel","sensationeel","sensueel","sereen","serieus","sex","sexy","simpel","simplistisch","slaaf","slaan","slachting","slachtoffer","slapend","slecht","slecht ingehouden","slechtste","slim","slinks","slonzig","sluw","smachten","smakeloos","smerig","smokkelen","snel","snel-start","snob","snotterend","snotterig","solide","spannende","sparen","speciaal","spectaculair","speelse","spelbreker","spervuur","spijker","spontaan","spotlight","stabiel","stap polarisatie","stap-voor-stap","stelen","sterk","sterk aanraden","stevige","stijgend","stijgende","stil","stoer","stoicijns","stom slagen","stomend","stoot","stop","stoppen","storm","straffen","stralend","strategie","streng","stressed","strijd","strijden","studies","stuipen","stuntelen","subliem","succes","succesvol","suffig","super","superbe","superieur","tank","technologie","tegenstelling","tekenen","teneergeslagen","terreur","terrorist","terug te betalen","terugbetalen","terugslag","tevreden","tijdige","toegeeflijk","toegeven","toegewijd","toename","toetakelen","tollen","tragedie","tragisch","transparantie","trauma","trefzekere","trend","triggers","triomf","trots","trucs","twijfel","twijfelachtig","twistziek","uit balans","uitbundig","uitdaging","uitgebreid","uitgehongerd","uitgelaten","uitgerust","uitzinnig","ultiem","undercover","uniek","up-sell","vaardigheid","val","valideren","valkuil","vandaag","vasthoudend","vechten","veelbelovende","veilig","veiligheid","venijnig","veraderlijk","verantwoordelijk","verbazend","verbazingwekkend","verbeelding","verbeterde","verblind","verblinden","verboden","verborgen","verdacht","verdampen","verdienen","verdoemd","verdomme","verdorven","verdrinken","vereenvoudigd","verergeren","vergelijk","vergeten","vergevend","verheffend","verkoop","verlamd","verlangen","verleidelijk","verleidelijke","verlicht","verliezer","verloren","vermijd","verminderde","vermoeide","vernietigen","verontrust","veroordelen","veroveren","verpakt","verpletterd","verpletteren","verplichting","verraderlijke","verrassend","verrassende","verrassing","verrast","verrukt","verschrikkelijk","verslaan","verspillen","verstrikt","vertrouwelijk","vertrouwen","vertrouwend","vervbodern","vervreemd","vervuld","vervullen","verwaand","verward","verwoestende","verwoesting","verzamelaar","verzekerd","verzet","verzettend","vet","vierdubbel","vijandig","vindingrijk","vloeibaar","vluchteling","volatiel","volledig","volledigheid","voor altijd","voordeel","voorproef","voortreffelijk","voorzichtig","vreemd","vreselijk","vrijheid","vrijlaten","vrolijk","vuil spel","vurig","waanzinnig","waanzinnige","waar over praat","waarde","waardevolle","waarheid","waarschijnlijk","waarschuwing","wachtend","walgelijk","wankelende","wantrouwend","wat niemand je vertelt","watertanden","weerzinwekkend","weerzinwekkende","weggever","weigeren","weinig bekend","wens","wereld","wild","wilskracht","winst","winstgevende","woedend","wonderful","wonderlijk","wraak","wraakzuchtig","wreed","wreedheid","wulpse","wurgen","zalig","zege","zeker","zeldzaam","zelfgenoegzaam","zelfhatende","zelfverzekerd","zelfvoorzienend","zen","zes-cijferige","ziedend","zielig","zinger","zinloos","zomaar","zonden","zonder vrees","zondig","zonnig","zorgeloos","zorgen zorg","zorgvuldig","zou","zuigen","zuinig","zwaartekracht","zwakke","zwarte markt","zweep","zwetend","zwijmelend"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":{"max-snippet":"-1","max-video-preview":"-1","max-image-preview":"large"},"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/t-safe.com\/nl\/wp-json\/wp\/v2\/pages\/5105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/t-safe.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/t-safe.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/t-safe.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/t-safe.com\/nl\/wp-json\/wp\/v2\/comments?post=5105"}],"version-history":[{"count":4,"href":"https:\/\/t-safe.com\/nl\/wp-json\/wp\/v2\/pages\/5105\/revisions"}],"predecessor-version":[{"id":17656,"href":"https:\/\/t-safe.com\/nl\/wp-json\/wp\/v2\/pages\/5105\/revisions\/17656"}],"wp:attachment":[{"href":"https:\/\/t-safe.com\/nl\/wp-json\/wp\/v2\/media?parent=5105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}